<!-- Start of gorentaride Zendesk Widget script -->
<p><script id="ze-snippet" src="https://static.zdassets.com/ekr/snippet.js?key=259d9e01-1965-43e7-b4cf-5a7c7889a8dd"> </script></p>
<!-- End of gorentaride Zendesk Widget script -->

{"id":869,"date":"2025-07-21T10:57:28","date_gmt":"2025-07-21T10:57:28","guid":{"rendered":"https:\/\/rentaride2go.com\/bookings\/rent-grid\/"},"modified":"2025-10-26T12:21:19","modified_gmt":"2025-10-26T16:21:19","slug":"rent-grid","status":"publish","type":"page","link":"https:\/\/www.gorentaride.com\/bookings\/rent-grid\/","title":{"rendered":"Vehicles"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><!-- Start of gorentaride Zendesk Widget script -->\r\n<p><script id=\"ze-snippet\" src=\"https:\/\/static.zdassets.com\/ekr\/snippet.js?key=259d9e01-1965-43e7-b4cf-5a7c7889a8dd\"> <\/script><\/p>\r\n<!-- End of gorentaride Zendesk Widget script -->\r\n<p>&nbsp;<\/p>\r\n<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading is-layout-constrained wp-block-group-is-layout-constrained\">Find Your Perfect Long-Term Rental<\/h2>\r\n\r\n\r\n\r\n<p>Browse our selection of premium vehicles available for extended rental periods<\/p>\r\n\r\n\r\n<form role=\"search\" method=\"get\" action=\"https:\/\/www.gorentaride.com\/bookings\/\" class=\"wp-block-search__button-outside wp-block-search__text-button wp-block-search\"    ><label class=\"wp-block-search__label\" for=\"wp-block-search__input-1\" >Search<\/label><div class=\"wp-block-search__inside-wrapper\" ><input class=\"wp-block-search__input\" id=\"wp-block-search__input-1\" placeholder=\"\" value=\"\" type=\"search\" name=\"s\" required \/><button aria-label=\"Search\" class=\"wp-block-search__button wp-element-button\" type=\"submit\" >Search<\/button><\/div><\/form><\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; [vc_row][vc_column][vc_column_text css=&#8221;&#8221;] Find Your Perfect Long-Term Rental Browse our selection of premium vehicles available for extended rental periods<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"property_list.php","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-869","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gorentaride.com\/bookings\/wp-json\/wp\/v2\/pages\/869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gorentaride.com\/bookings\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gorentaride.com\/bookings\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gorentaride.com\/bookings\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gorentaride.com\/bookings\/wp-json\/wp\/v2\/comments?post=869"}],"version-history":[{"count":74,"href":"https:\/\/www.gorentaride.com\/bookings\/wp-json\/wp\/v2\/pages\/869\/revisions"}],"predecessor-version":[{"id":45171,"href":"https:\/\/www.gorentaride.com\/bookings\/wp-json\/wp\/v2\/pages\/869\/revisions\/45171"}],"wp:attachment":[{"href":"https:\/\/www.gorentaride.com\/bookings\/wp-json\/wp\/v2\/media?parent=869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}